{"id":4168,"date":"2026-03-18T14:13:55","date_gmt":"2026-03-18T13:13:55","guid":{"rendered":"https:\/\/www.experta.com.ar\/?p=4168"},"modified":"2026-03-20T19:09:46","modified_gmt":"2026-03-20T18:09:46","slug":"prisa-enemiga","status":"publish","type":"post","link":"https:\/\/www.experta.com.ar\/index.php\/prisa-enemiga\/","title":{"rendered":"PRISA ENEMIGA"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Hoy en d\u00eda, en varias ocasiones, <\/span><b>nos sentimos en un <\/b><b><i>loop <\/i><\/b><b>continuo a pura <\/b><b>prisa<\/b><span style=\"font-weight: 400;\">. Siempre <\/span><b>apurados de aqu\u00ed para all\u00e1, yendo de una actividad a otra, de una reuni\u00f3n a otra, o incluso en la virtualidad, \u00a1de una <\/b><b><i>call <\/i><\/b><b>a otra!<\/b><span style=\"font-weight: 400;\"> Y as\u00ed se pasan los d\u00edas a las corridas entre nuestros negocios, trabajo y, claro, nuestra vida. <\/span><b>Estar siempre apurados no es bueno para nada: desgasta y mucho<\/b><span style=\"font-weight: 400;\">. <\/span><b>La <\/b><b>prisa<\/b><b> es enemiga de los negocios, pero lo m\u00e1s importante es que es la peor amiga de la tranquilidad<\/b><span style=\"font-weight: 400;\">. <\/span><span style=\"font-weight: 400;\">\u00bfPor qu\u00e9 vivimos siempre apurados?<\/span><span style=\"font-weight: 400;\"> La respuesta puede estar atada al contexto y tambi\u00e9n a <\/span><b>la falsa creencia de que quien est\u00e1 todo el d\u00eda de aqu\u00ed para all\u00e1 es productivo y quedarse quieto no est\u00e1 \u201cbien visto\u201d<\/b><span style=\"font-weight: 400;\">. Ahora, \u00bfC\u00f3mo bajar revoluciones? \u00bfC\u00f3mo aprender a vivir sin <\/span><span style=\"font-weight: 400;\">prisa<\/span><span style=\"font-weight: 400;\"> constante en un mundo y contexto que marcan un ritmo vertiginoso?<\/span><\/p>\n<p>&nbsp;<\/p>\n<hr style=\"border: solid 1px #727272;\" \/>\n<p><b>\u00a0<\/b><\/p>\n<p><b>AGENDAS M\u00c1S LIVIANAS<\/b><\/p>\n<p><b>La energ\u00eda es el motor de las personas<\/b><span style=\"font-weight: 400;\"> y tenerla es superbueno y hasta vital para lo que hacemos, <\/span><b>pero como todo lo bueno \u2013en \u201cexceso\u201d\u2013 puede traer problemas<\/b><span style=\"font-weight: 400;\">. <\/span><b>Cuando nos sentimos con energ\u00eda llenamos nuestros d\u00edas de reuniones, compromisos\u2026 y no dejamos un solo hueco libre<\/b><span style=\"font-weight: 400;\">. Sin embargo, <\/span><b>una agenda llena de prisas fren\u00e9ticas agota en todo sentido: f\u00edsica y mentalmente. Y no hay energ\u00eda que pueda ir contra eso<\/b><span style=\"font-weight: 400;\">. A su vez, <\/span><b>si estamos agotados nada bueno puede surgir.\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400;\">\u00bfLa prisa mejora o empeora los resultados? \u00bfC\u00f3mo afecta al trabajo y los negocios?<\/span><span style=\"font-weight: 400;\"> Sin duda <\/span><b>la <\/b><b>prisa<\/b><b> empeora los resultados. Si hacemos todo r\u00e1pido lo m\u00e1s probable es que en el medio cometamos errores,<\/b><span style=\"font-weight: 400;\"> ya que al no parar y vivir sin pausa <\/span><b>el <\/b><b>estr\u00e9s<\/b><b> se apodera de nosotros y no nos permite pensar con claridad.<\/b><span style=\"font-weight: 400;\"> Por lo tanto, <\/span><b>hay que frenar y pensar las jornadas con m\u00e1s pausas y sin tantas corridas en la rutina laboral.<\/b> <span style=\"font-weight: 400;\">\u00bfC\u00f3mo bajar el ritmo sin perder productividad?<\/span><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Algunas sugerencias que pueden colaborar en este sentido:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Pausar antes de comprometerse con algo<\/b><span style=\"font-weight: 400;\">. Antes de decir \u201cs\u00ed\u201d a todo lo que nos piden evaluar si vamos a tener el tiempo para hacerlo o no. Tambi\u00e9n reflexionar acerca de si ese pedido se alinea con nuestros objetivos o proyectos, o si le estamos resolviendo algo a alguien m\u00e1s y esa acci\u00f3n no nos suma a nosotros.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Bloquear tiempo en la agenda<\/b><span style=\"font-weight: 400;\">. Reservar en el calendario unos momentos al d\u00eda para sacar el pie del acelerador, relajarse y despejar la mente. Esto sirve tambi\u00e9n para la <\/span><span style=\"font-weight: 400;\">productividad<\/span><span style=\"font-weight: 400;\">: podemos ponernos al d\u00eda con alg\u00fan proyecto que necesita de reflexi\u00f3n, pensar nuevas ideas, crear. La cabeza m\u00e1s liviana es muy productiva.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Darle el tiempo que requieren las decisiones importantes<\/b><span style=\"font-weight: 400;\">. Muchas veces la <\/span><span style=\"font-weight: 400;\">prisa<\/span><span style=\"font-weight: 400;\"> nos lleva puestos y nos hace tomar \u2013en el apuro\u2013 decisiones no del todo acertadas. Si es algo que puede tener zonas grises y necesita de nuestro tiempo de reflexi\u00f3n, darle ese espacio. Permitirse analizarlo y dar respuesta al d\u00eda siguiente, por ejemplo.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Tener <\/b><b>gesti\u00f3n del tiempo<\/b><span style=\"font-weight: 400;\">. Gestionar el tiempo que tenemos en la jornada es fundamental. Hay que poder dimensionarlo para no abarcar m\u00e1s de lo que el tiempo f\u00edsico nos brinda.\u00a0<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\"><br \/>\nPara finalizar es importante <\/span><b>hacernos la siguiente pregunta: <\/b><b>\u00bfQu\u00e9 se gana al vivir sin prisa constante?<\/b> <span style=\"font-weight: 400;\">Seguramente la respuesta <\/span><b>est\u00e9 en <\/b><b>bienestar, equilibrio, enfoque<\/b><b> y una mejor <\/b><b>calidad de vida<\/b><span style=\"font-weight: 400;\">. Despu\u00e9s de todo, de eso trata. Vivir mejor y con m\u00e1s plenitud.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy en d\u00eda, en varias ocasiones, nos sentimos en un loop continuo a pura prisa. Siempre apurados de aqu\u00ed para all\u00e1, yendo de una actividad a otra, de una reuni\u00f3n a otra, o incluso en la virtualidad, \u00a1de una call a otra! Y as\u00ed se pasan los d\u00edas a las corridas entre nuestros negocios, trabajo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4170,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-4168","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calidad-de-vida"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.experta.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/4168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.experta.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.experta.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.experta.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.experta.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=4168"}],"version-history":[{"count":3,"href":"https:\/\/www.experta.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/4168\/revisions"}],"predecessor-version":[{"id":4178,"href":"https:\/\/www.experta.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/4168\/revisions\/4178"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.experta.com.ar\/index.php\/wp-json\/wp\/v2\/media\/4170"}],"wp:attachment":[{"href":"https:\/\/www.experta.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=4168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.experta.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=4168"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.experta.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=4168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}